{"id":61429,"date":"2026-06-07T04:42:52","date_gmt":"2026-06-07T04:42:52","guid":{"rendered":"https:\/\/euler.euclid.int\/veelgestelde-vragen\/"},"modified":"2026-06-07T04:42:52","modified_gmt":"2026-06-07T04:42:52","slug":"veelgestelde-vragen","status":"publish","type":"post","link":"https:\/\/euler.euclid.int\/nl\/veelgestelde-vragen\/","title":{"rendered":"Veelgestelde vragen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[541],"tags":[],"class_list":["post-61429","post","type-post","status-publish","format-standard","hentry","category-ongecategoriseerd"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veelgestelde vragen - EFMU: The Euler-Franeker Memorial University and Institute<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/euler.euclid.int\/nl\/veelgestelde-vragen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veelgestelde vragen - EFMU: The Euler-Franeker Memorial University and Institute\" \/>\n<meta property=\"og:url\" content=\"https:\/\/euler.euclid.int\/nl\/veelgestelde-vragen\/\" \/>\n<meta property=\"og:site_name\" content=\"EFMU: The Euler-Franeker Memorial University and Institute\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-07T04:42:52+00:00\" \/>\n<meta name=\"author\" content=\"siteadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"siteadmin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/euler.euclid.int\\\/nl\\\/veelgestelde-vragen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euler.euclid.int\\\/nl\\\/veelgestelde-vragen\\\/\"},\"author\":{\"name\":\"siteadmin\",\"@id\":\"https:\\\/\\\/euler.euclid.int\\\/#\\\/schema\\\/person\\\/531e22349e1c4ceebc42c9c4467aef6c\"},\"headline\":\"Veelgestelde vragen\",\"datePublished\":\"2026-06-07T04:42:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/euler.euclid.int\\\/nl\\\/veelgestelde-vragen\\\/\"},\"wordCount\":2,\"articleSection\":[\"Ongecategoriseerd\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/euler.euclid.int\\\/nl\\\/veelgestelde-vragen\\\/\",\"url\":\"https:\\\/\\\/euler.euclid.int\\\/nl\\\/veelgestelde-vragen\\\/\",\"name\":\"Veelgestelde vragen - EFMU: The Euler-Franeker Memorial University and Institute\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euler.euclid.int\\\/#website\"},\"datePublished\":\"2026-06-07T04:42:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/euler.euclid.int\\\/#\\\/schema\\\/person\\\/531e22349e1c4ceebc42c9c4467aef6c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/euler.euclid.int\\\/nl\\\/veelgestelde-vragen\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/euler.euclid.int\\\/nl\\\/veelgestelde-vragen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/euler.euclid.int\\\/nl\\\/veelgestelde-vragen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/euler.euclid.int\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veelgestelde vragen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/euler.euclid.int\\\/#website\",\"url\":\"https:\\\/\\\/euler.euclid.int\\\/\",\"name\":\"EFMU: The Euler-Franeker Memorial University and Institute\",\"description\":\"Academic and Research Excellence inspired by the Legacy of L. Euler and the University of Franeker\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/euler.euclid.int\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/euler.euclid.int\\\/#\\\/schema\\\/person\\\/531e22349e1c4ceebc42c9c4467aef6c\",\"name\":\"siteadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a5c18c63c767955243dfce34a8aff0de183d1d16f3641e8305d9c6721cd1751?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a5c18c63c767955243dfce34a8aff0de183d1d16f3641e8305d9c6721cd1751?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a5c18c63c767955243dfce34a8aff0de183d1d16f3641e8305d9c6721cd1751?s=96&d=mm&r=g\",\"caption\":\"siteadmin\"},\"url\":\"https:\\\/\\\/euler.euclid.int\\\/nl\\\/author\\\/siteadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veelgestelde vragen - EFMU: The Euler-Franeker Memorial University and Institute","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/euler.euclid.int\/nl\/veelgestelde-vragen\/","og_locale":"nl_NL","og_type":"article","og_title":"Veelgestelde vragen - EFMU: The Euler-Franeker Memorial University and Institute","og_url":"https:\/\/euler.euclid.int\/nl\/veelgestelde-vragen\/","og_site_name":"EFMU: The Euler-Franeker Memorial University and Institute","article_published_time":"2026-06-07T04:42:52+00:00","author":"siteadmin","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"siteadmin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/euler.euclid.int\/nl\/veelgestelde-vragen\/#article","isPartOf":{"@id":"https:\/\/euler.euclid.int\/nl\/veelgestelde-vragen\/"},"author":{"name":"siteadmin","@id":"https:\/\/euler.euclid.int\/#\/schema\/person\/531e22349e1c4ceebc42c9c4467aef6c"},"headline":"Veelgestelde vragen","datePublished":"2026-06-07T04:42:52+00:00","mainEntityOfPage":{"@id":"https:\/\/euler.euclid.int\/nl\/veelgestelde-vragen\/"},"wordCount":2,"articleSection":["Ongecategoriseerd"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/euler.euclid.int\/nl\/veelgestelde-vragen\/","url":"https:\/\/euler.euclid.int\/nl\/veelgestelde-vragen\/","name":"Veelgestelde vragen - EFMU: The Euler-Franeker Memorial University and Institute","isPartOf":{"@id":"https:\/\/euler.euclid.int\/#website"},"datePublished":"2026-06-07T04:42:52+00:00","author":{"@id":"https:\/\/euler.euclid.int\/#\/schema\/person\/531e22349e1c4ceebc42c9c4467aef6c"},"breadcrumb":{"@id":"https:\/\/euler.euclid.int\/nl\/veelgestelde-vragen\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/euler.euclid.int\/nl\/veelgestelde-vragen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/euler.euclid.int\/nl\/veelgestelde-vragen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/euler.euclid.int\/"},{"@type":"ListItem","position":2,"name":"Veelgestelde vragen"}]},{"@type":"WebSite","@id":"https:\/\/euler.euclid.int\/#website","url":"https:\/\/euler.euclid.int\/","name":"EFMU: The Euler-Franeker Memorial University and Institute","description":"Academic and Research Excellence inspired by the Legacy of L. Euler and the University of Franeker","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/euler.euclid.int\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/euler.euclid.int\/#\/schema\/person\/531e22349e1c4ceebc42c9c4467aef6c","name":"siteadmin","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/2a5c18c63c767955243dfce34a8aff0de183d1d16f3641e8305d9c6721cd1751?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2a5c18c63c767955243dfce34a8aff0de183d1d16f3641e8305d9c6721cd1751?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2a5c18c63c767955243dfce34a8aff0de183d1d16f3641e8305d9c6721cd1751?s=96&d=mm&r=g","caption":"siteadmin"},"url":"https:\/\/euler.euclid.int\/nl\/author\/siteadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/euler.euclid.int\/nl\/wp-json\/wp\/v2\/posts\/61429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euler.euclid.int\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/euler.euclid.int\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/euler.euclid.int\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/euler.euclid.int\/nl\/wp-json\/wp\/v2\/comments?post=61429"}],"version-history":[{"count":0,"href":"https:\/\/euler.euclid.int\/nl\/wp-json\/wp\/v2\/posts\/61429\/revisions"}],"wp:attachment":[{"href":"https:\/\/euler.euclid.int\/nl\/wp-json\/wp\/v2\/media?parent=61429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/euler.euclid.int\/nl\/wp-json\/wp\/v2\/categories?post=61429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/euler.euclid.int\/nl\/wp-json\/wp\/v2\/tags?post=61429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}